{"id":60164,"date":"2020-11-25T13:23:37","date_gmt":"2020-11-25T09:23:37","guid":{"rendered":"https:\/\/ptn.primetime.ge\/?p=60164"},"modified":"2020-11-25T15:21:50","modified_gmt":"2020-11-25T11:21:50","slug":"sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas","status":"publish","type":"post","link":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/","title":{"rendered":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1"},"content":{"rendered":"<p>\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1 <span class=\"nanospell-typo\">\u10d3\u10d4-\u10e4\u10d0\u10e5\u10e2\u10dd<\/span> <span class=\"nanospell-typo\">\u10d0\u10dc\u10d4\u10e5\u10e1\u10d8\u10d8\u10e1\u10d0\u10d9\u10d4\u10dc<\/span> \u10d2\u10d0\u10d3\u10d0\u10d3\u10d2\u10db\u10e3\u10da \u10db\u10dd\u10e0\u10d8\u10d2 \u10e3\u10d9\u10d0\u10dc\u10dd\u10dc\u10dd \u10dc\u10d0\u10d1\u10d8\u10ef\u10e1, \u10e0\u10dd\u10db\u10d4\u10da\u10d8\u10ea \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d2\u10d0\u10dc\u10e3\u10e7\u10dd\u10e4\u10d4\u10da\u10d8 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10d4\u10d1\u10d8\u10e1 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e1\u10d0\u10db\u10ee\u10d4\u10d3\u10e0\u10dd, \u10de\u10dd\u10da\u10d8\u10e2\u10d8\u10d9\u10e3\u10e0, \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0 \u10d3\u10d0 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0 \u10e1\u10d8\u10e1\u10e2\u10d4\u10db\u10d0\u10e8\u10d8 \u10d4\u10e2\u10d0\u10de\u10dd\u10d1\u10e0\u10d8\u10d5\u10d0\u10d3 \u10d8\u10dc\u10e2\u10d4\u10d2\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1 \u10d4\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d0\u201c &#8211; \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8\u10d0 \u10dc\u10d0\u10d7\u10e5\u10d5\u10d0\u10db\u10d8, \u10e0\u10dd\u10db\u10d4\u10da\u10e1\u10d0\u10ea \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7 \u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e1.<\/p>\n<p>\u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8 \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0, \u10e0\u10dd\u10db \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10e1\u10dd\u10ee\u10e3\u10db\u10d8\u10e1 \u10e1\u10d0\u10dd\u10d9\u10e3\u10de\u10d0\u10ea\u10d8\u10dd \u10e0\u10d4\u10df\u10d8\u10db\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 2014 \u10ec\u10da\u10d8\u10e1 \u10dc\u10dd\u10d4\u10db\u10d1\u10d4\u10e0\u10e8\u10d8 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da\u10d8 \u10d4.\u10ec. \u201e\u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u201c \u10db\u10dd\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10dd\u10d1\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10e1\u10e2\u10e0\u10d0\u10e2\u10d4\u10d2\u10d8\u10e3\u10da\u10d8 \u10de\u10d0\u10e0\u10e2\u10dc\u10d8\u10dd\u10e0\u10dd\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10d8\u10e1\u10d4\u10d5\u10d4, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10db\u10d8\u10e1 \u10e4\u10d0\u10e0\u10d2\u10da\u10d4\u10d1\u10e8\u10d8 \u10e8\u10d4\u10db\u10e3\u10e8\u10d0\u10d5\u10d4\u10d1\u10e3\u10da\u10d8 \u10e7\u10d5\u10d4\u10da\u10d0 \u10d4.\u10ec. \u201e\u10e8\u10d4\u10d7\u10d0\u10dc\u10ee\u10db\u10d4\u10d1\u10d0\u201c, \u201e\u10db\u10d4\u10db\u10dd\u10e0\u10d0\u10dc\u10d3\u10e3\u10db\u10d8\u201c \u10d7\u10e3 \u201e\u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d0\u201c \u10e3\u10d9\u10d0\u10dc\u10dd\u10dc\u10dd\u10d0 \u10d3\u10d0 \u10d5\u10d4\u10e0 \u10ec\u10d0\u10e0\u10db\u10dd\u10e8\u10dd\u10d1\u10e1 \u10e0\u10d0\u10d8\u10db\u10d4 \u10e1\u10d0\u10db\u10d0\u10e0\u10d7\u10da\u10d4\u10d1\u10e0\u10d8\u10d5 \u10e8\u10d4\u10d3\u10d4\u10d2\u10e1.<\/p>\n<blockquote><p><strong><em>\u201e\u10db\u10e1\u10d2\u10d0\u10d5\u10e1\u10d8 \u10de\u10e0\u10dd\u10d5\u10dd\u10d9\u10d0\u10ea\u10d8\u10e3\u10da\u10d8 \u10dc\u10d0\u10d1\u10d8\u10ef\u10d4\u10d1\u10d8\u10d7\u10d0 \u10d3\u10d0 \u10f0\u10d8\u10d1\u10e0\u10d8\u10d3\u10e3\u10da\u10d8 \u10dd\u10db\u10d8\u10e1 \u10d8\u10dc\u10e1\u10e2\u10e0\u10e3\u10db\u10d4\u10dc\u10e2\u10d4\u10d1\u10d8\u10d7 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0 \u10e3\u10ee\u10d4\u10e8\u10d0\u10d3 \u10d0\u10e0\u10e6\u10d5\u10d4\u10d5\u10e1 \u10e1\u10d0\u10d4\u10e0\u10d7\u10d0\u10e8\u10dd\u10e0\u10d8\u10e1\u10dd \u10e1\u10d0\u10db\u10d0\u10e0\u10d7\u10da\u10d8\u10e1 \u10e4\u10e3\u10dc\u10d3\u10d0\u10db\u10d4\u10dc\u10e2\u10e3\u10e0 \u10dc\u10dd\u10e0\u10db\u10d4\u10d1\u10e1\u10d0 \u10d3\u10d0 \u10de\u10e0\u10d8\u10dc\u10ea\u10d8\u10de\u10d4\u10d1\u10e1, \u10ee\u10d4\u10da\u10e7\u10dd\u10e4\u10e1 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10e1\u10e3\u10d5\u10d4\u10e0\u10d4\u10dc\u10d8\u10e2\u10d4\u10e2\u10e1\u10d0 \u10d3\u10d0 \u10e2\u10d4\u10e0\u10d8\u10e2\u10dd\u10e0\u10d8\u10e3\u10da \u10db\u10d7\u10da\u10d8\u10d0\u10dc\u10dd\u10d1\u10d0\u10e1 \u10d3\u10d0 \u10e1\u10d4\u10e0\u10d8\u10dd\u10d6\u10e3\u10da \u10e1\u10d0\u10e4\u10e0\u10d7\u10ee\u10d4\u10e1 \u10e3\u10e5\u10db\u10dc\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e8\u10d8 \u10db\u10e8\u10d5\u10d8\u10d3\u10dd\u10d1\u10d0\u10e1 \u10d3\u10d0 \u10e3\u10e1\u10d0\u10e4\u10e0\u10d7\u10ee\u10dd\u10d4\u10d1\u10d0\u10e1.\u10db\u10dd\u10d5\u10e3\u10ec\u10dd\u10d3\u10d4\u10d1\u10d7 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1, \u10e8\u10d4\u10ec\u10e7\u10d5\u10d8\u10e2\u10dd\u10e1 \u10d3\u10d4\u10e1\u10e2\u10e0\u10e3\u10e5\u10ea\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10e5\u10db\u10d4\u10d3\u10d4\u10d1\u10d4\u10d1\u10d8 \u10d3\u10d0 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da\u10d8 \u10e2\u10d4\u10e0\u10d8\u10e2\u10dd\u10e0\u10d8\u10d4\u10d1\u10d8\u10e1 \u10e4\u10d0\u10e5\u10e2\u10dd\u10d1\u10e0\u10d8\u10d5\u10d8 <span class=\"nanospell-typo\">\u10d0\u10dc\u10d4\u10e5\u10e1\u10d8\u10d8\u10e1\u10d0\u10d9\u10d4\u10dc<\/span> \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10e3\u10d9\u10d0\u10dc\u10dd\u10dc\u10dd \u10dc\u10d0\u10d1\u10d8\u10ef\u10d4\u10d1\u10d8, \u10e8\u10d4\u10d0\u10e1\u10e0\u10e3\u10da\u10dd\u10e1 \u10d4\u10d5\u10e0\u10dd\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d8\u10e1 \u10e8\u10e3\u10d0\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d8\u10d7 2008 \u10ec\u10da\u10d8\u10e1 12 \u10d0\u10d2\u10d5\u10d8\u10e1\u10e2\u10dd\u10e1 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da\u10d8 \u10ea\u10d4\u10ea\u10ee\u10da\u10d8\u10e1 \u10e8\u10d4\u10ec\u10e7\u10d5\u10d4\u10e2\u10d8\u10e1 \u10e8\u10d4\u10d7\u10d0\u10dc\u10ee\u10db\u10d4\u10d1\u10d8\u10d7 \u10dc\u10d0\u10d9\u10d8\u10e1\u10e0\u10d8 \u10d5\u10d0\u10da\u10d3\u10d4\u10d1\u10e3\u10da\u10d4\u10d1\u10d4\u10d1\u10d8, \u10d2\u10d0\u10d8\u10e7\u10d5\u10d0\u10dc\u10dd\u10e1 \u10d7\u10d0\u10d5\u10d8\u10e1\u10d8 \u10e1\u10d0\u10db\u10ee\u10d4\u10d3\u10e0\u10dd \u10eb\u10d0\u10da\u10d4\u10d1\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10e2\u10d4\u10e0\u10d8\u10e2\u10dd\u10e0\u10d8\u10d8\u10d3\u10d0\u10dc \u10d3\u10d0 \u10ee\u10d4\u10da\u10d8 \u10d0\u10e0 \u10e8\u10d4\u10e3\u10e8\u10d0\u10da\u10dd\u10e1 \u10d0\u10d3\u10d2\u10d8\u10da\u10d6\u10d4 \u10e3\u10e1\u10d0\u10e4\u10e0\u10d7\u10ee\u10dd\u10d4\u10d1\u10d8\u10e1 \u10e1\u10d0\u10d4\u10e0\u10d7\u10d0\u10e8\u10dd\u10e0\u10d8\u10e1\u10dd \u10db\u10d4\u10e5\u10d0\u10dc\u10d8\u10d6\u10db\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e5\u10db\u10dc\u10d0\u10e1\u201c, &#8211; \u10dc\u10d0\u10d7\u10e5\u10d5\u10d0\u10db\u10d8\u10d0 \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8.<\/em><\/strong><\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1 \u10d3\u10d4-\u10e4\u10d0\u10e5\u10e2\u10dd \u10d0\u10dc\u10d4\u10e5\u10e1\u10d8\u10d8\u10e1\u10d0\u10d9\u10d4\u10dc \u10d2\u10d0\u10d3\u10d0\u10d3\u10d2\u10db\u10e3\u10da \u10db\u10dd\u10e0\u10d8\u10d2 \u10e3\u10d9\u10d0\u10dc\u10dd\u10dc\u10dd \u10dc\u10d0\u10d1\u10d8\u10ef\u10e1, \u10e0\u10dd\u10db\u10d4\u10da\u10d8\u10ea \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d2\u10d0\u10dc\u10e3\u10e7\u10dd\u10e4\u10d4\u10da\u10d8 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10d4\u10d1\u10d8\u10e1 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e1\u10d0\u10db\u10ee\u10d4\u10d3\u10e0\u10dd, \u10de\u10dd\u10da\u10d8\u10e2\u10d8\u10d9\u10e3\u10e0, \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0 \u10d3\u10d0 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0 \u10e1\u10d8\u10e1\u10e2\u10d4\u10db\u10d0\u10e8\u10d8 \u10d4\u10e2\u10d0\u10de\u10dd\u10d1\u10e0\u10d8\u10d5\u10d0\u10d3 \u10d8\u10dc\u10e2\u10d4\u10d2\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1 \u10d4\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d0\u201c &#8211; \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8\u10d0 \u10dc\u10d0\u10d7\u10e5\u10d5\u10d0\u10db\u10d8, \u10e0\u10dd\u10db\u10d4\u10da\u10e1\u10d0\u10ea \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 [&hellip;]<\/p>","protected":false},"author":18,"featured_media":60167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[1445,541,100,935],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1 - PTN.GE<\/title>\n<meta name=\"description\" content=\"\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1 - PTN.GE\" \/>\n<meta property=\"og:description\" content=\"\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/\" \/>\n<meta property=\"og:site_name\" content=\"PTN.GE\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T09:23:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T11:21:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"salome\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/ptn.primetime.ge\/#organization\",\"name\":\"PTN.GE\",\"url\":\"https:\/\/ptn.primetime.ge\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ptn.primetime.ge\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png\",\"contentUrl\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png\",\"width\":250,\"height\":250,\"caption\":\"PTN.GE\"},\"image\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ptn.primetime.ge\/#website\",\"url\":\"https:\/\/ptn.primetime.ge\/\",\"name\":\"PTN.GE\",\"description\":\"\\u10e1\\u10d0\\u10d8\\u10dc\\u10e4\\u10dd\\u10e0\\u10db\\u10d0\\u10ea\\u10d8\\u10dd \\u10de\\u10dd\\u10e0\\u10e2\\u10d0\\u10da\\u10d8\",\"publisher\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ptn.primetime.ge\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg\",\"contentUrl\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg\",\"width\":654,\"height\":523},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage\",\"url\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/\",\"name\":\"\\u10e1\\u10d0\\u10d2\\u10d0\\u10e0\\u10d4\\u10dd \\u10e3\\u10ec\\u10e7\\u10d4\\u10d1\\u10d0 \\u10d2\\u10db\\u10dd\\u10d1\\u10e1, \\u10e0\\u10e3\\u10e1\\u10d4\\u10d7\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10dd\\u10d9\\u10e3\\u10de\\u10d8\\u10e0\\u10d4\\u10d1\\u10e3\\u10da \\u10d0\\u10e4\\u10ee\\u10d0\\u10d6\\u10d4\\u10d7\\u10e1 \\u10e8\\u10dd\\u10e0\\u10d8\\u10e1 \\u10d4\\u10e0\\u10d7\\u10d8\\u10d0\\u10dc\\u10d8 \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d3\\u10d0 \\u10d4\\u10d9\\u10dd\\u10dc\\u10dd\\u10db\\u10d8\\u10d9\\u10e3\\u10e0\\u10d8 \\u10e1\\u10d8\\u10d5\\u10e0\\u10ea\\u10d8\\u10e1 \\u10e4\\u10dd\\u10e0\\u10db\\u10d8\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10de\\u10e0\\u10dd\\u10d2\\u10e0\\u10d0\\u10db\\u10d8\\u10e1 \\u10d3\\u10d0\\u10db\\u10e2\\u10d9\\u10d8\\u10ea\\u10d4\\u10d1\\u10d0\\u10e1 - PTN.GE\",\"isPartOf\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage\"},\"datePublished\":\"2020-11-25T09:23:37+00:00\",\"dateModified\":\"2020-11-25T11:21:50+00:00\",\"description\":\"\\u201e\\u10e0\\u10e3\\u10e1\\u10d4\\u10d7\\u10d8\\u10e1 \\u10e4\\u10d4\\u10d3\\u10d4\\u10e0\\u10d0\\u10ea\\u10d8\\u10d0\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10dd\\u10d9\\u10e3\\u10de\\u10d8\\u10e0\\u10d4\\u10d1\\u10e3\\u10da \\u10d0\\u10e4\\u10ee\\u10d0\\u10d6\\u10d4\\u10d7\\u10d8\\u10e1 \\u10e0\\u10d4\\u10d2\\u10d8\\u10dd\\u10dc\\u10e1 \\u10e8\\u10dd\\u10e0\\u10d8\\u10e1 \\u10d4\\u10e0\\u10d7\\u10d8\\u10d0\\u10dc\\u10d8 \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d3\\u10d0 \\u10d4\\u10d9\\u10dd\\u10dc\\u10dd\\u10db\\u10d8\\u10d9\\u10e3\\u10e0\\u10d8 \\u10e1\\u10d8\\u10d5\\u10e0\\u10ea\\u10d8\\u10e1 \\u10e4\\u10dd\\u10e0\\u10db\\u10d8\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10de\\u10e0\\u10dd\\u10d2\\u10e0\\u10d0\\u10db\\u10d8\\u10e1 \\u10d3\\u10d0\\u10db\\u10e2\\u10d9\\u10d8\\u10ea\\u10d4\\u10d1\\u10d0 \\u10ec\\u10d0\\u10e0\\u10db\\u10dd\\u10d0\\u10d3\\u10d2\\u10d4\\u10dc\\u10e1\",\"breadcrumb\":{\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ptn.primetime.ge\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u10e1\\u10d0\\u10d2\\u10d0\\u10e0\\u10d4\\u10dd \\u10e3\\u10ec\\u10e7\\u10d4\\u10d1\\u10d0 \\u10d2\\u10db\\u10dd\\u10d1\\u10e1, \\u10e0\\u10e3\\u10e1\\u10d4\\u10d7\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10dd\\u10d9\\u10e3\\u10de\\u10d8\\u10e0\\u10d4\\u10d1\\u10e3\\u10da \\u10d0\\u10e4\\u10ee\\u10d0\\u10d6\\u10d4\\u10d7\\u10e1 \\u10e8\\u10dd\\u10e0\\u10d8\\u10e1 \\u10d4\\u10e0\\u10d7\\u10d8\\u10d0\\u10dc\\u10d8 \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d3\\u10d0 \\u10d4\\u10d9\\u10dd\\u10dc\\u10dd\\u10db\\u10d8\\u10d9\\u10e3\\u10e0\\u10d8 \\u10e1\\u10d8\\u10d5\\u10e0\\u10ea\\u10d8\\u10e1 \\u10e4\\u10dd\\u10e0\\u10db\\u10d8\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10de\\u10e0\\u10dd\\u10d2\\u10e0\\u10d0\\u10db\\u10d8\\u10e1 \\u10d3\\u10d0\\u10db\\u10e2\\u10d9\\u10d8\\u10ea\\u10d4\\u10d1\\u10d0\\u10e1\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage\"},\"author\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#\/schema\/person\/f43bc888f884ee76c0ce504279c2c399\"},\"headline\":\"\\u10e1\\u10d0\\u10d2\\u10d0\\u10e0\\u10d4\\u10dd \\u10e3\\u10ec\\u10e7\\u10d4\\u10d1\\u10d0 \\u10d2\\u10db\\u10dd\\u10d1\\u10e1, \\u10e0\\u10e3\\u10e1\\u10d4\\u10d7\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10dd\\u10d9\\u10e3\\u10de\\u10d8\\u10e0\\u10d4\\u10d1\\u10e3\\u10da \\u10d0\\u10e4\\u10ee\\u10d0\\u10d6\\u10d4\\u10d7\\u10e1 \\u10e8\\u10dd\\u10e0\\u10d8\\u10e1 \\u10d4\\u10e0\\u10d7\\u10d8\\u10d0\\u10dc\\u10d8 \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d3\\u10d0 \\u10d4\\u10d9\\u10dd\\u10dc\\u10dd\\u10db\\u10d8\\u10d9\\u10e3\\u10e0\\u10d8 \\u10e1\\u10d8\\u10d5\\u10e0\\u10ea\\u10d8\\u10e1 \\u10e4\\u10dd\\u10e0\\u10db\\u10d8\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10de\\u10e0\\u10dd\\u10d2\\u10e0\\u10d0\\u10db\\u10d8\\u10e1 \\u10d3\\u10d0\\u10db\\u10e2\\u10d9\\u10d8\\u10ea\\u10d4\\u10d1\\u10d0\\u10e1\",\"datePublished\":\"2020-11-25T09:23:37+00:00\",\"dateModified\":\"2020-11-25T11:21:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage\"},\"wordCount\":3,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#organization\"},\"image\":{\"@id\":\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg\",\"keywords\":[\"\\u10d3\\u10d4 \\u10e4\\u10d0\\u10e5\\u10e2\\u10dd \\u10d0\\u10e4\\u10ee\\u10d0\\u10d6\\u10d4\\u10d7\\u10d8\",\"\\u10dd\\u10d9\\u10e3\\u10de\\u10d0\\u10ea\\u10d8\\u10d0\",\"\\u10e0\\u10e3\\u10e1\\u10d4\\u10d7\\u10d8\",\"\\u10e1\\u10d0\\u10d2\\u10d0\\u10e0\\u10d4\\u10dd \\u10e1\\u10d0\\u10e5\\u10db\\u10d4\\u10d7\\u10d0 \\u10e1\\u10d0\\u10db\\u10d8\\u10dc\\u10d8\\u10e1\\u10e2\\u10e0\\u10dd\"],\"articleSection\":[\"\\u10de\\u10dd\\u10da\\u10d8\\u10e2\\u10d8\\u10d9\\u10d0\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ptn.primetime.ge\/#\/schema\/person\/f43bc888f884ee76c0ce504279c2c399\",\"name\":\"salome\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ptn.primetime.ge\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ce7c36b03612e72bdefcb1a00658c5b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ce7c36b03612e72bdefcb1a00658c5b0?s=96&d=mm&r=g\",\"caption\":\"salome\"},\"url\":\"https:\/\/ptn.primetime.ge\/en\/author\/salome\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1 - PTN.GE","description":"\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/","og_locale":"en_US","og_type":"article","og_title":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1 - PTN.GE","og_description":"\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1","og_url":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/","og_site_name":"PTN.GE","article_published_time":"2020-11-25T09:23:37+00:00","article_modified_time":"2020-11-25T11:21:50+00:00","og_image":[{"width":654,"height":523,"url":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"salome"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/ptn.primetime.ge\/#organization","name":"PTN.GE","url":"https:\/\/ptn.primetime.ge\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/ptn.primetime.ge\/#logo","inLanguage":"en-US","url":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png","contentUrl":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png","width":250,"height":250,"caption":"PTN.GE"},"image":{"@id":"https:\/\/ptn.primetime.ge\/#logo"}},{"@type":"WebSite","@id":"https:\/\/ptn.primetime.ge\/#website","url":"https:\/\/ptn.primetime.ge\/","name":"PTN.GE","description":"\u10e1\u10d0\u10d8\u10dc\u10e4\u10dd\u10e0\u10db\u10d0\u10ea\u10d8\u10dd \u10de\u10dd\u10e0\u10e2\u10d0\u10da\u10d8","publisher":{"@id":"https:\/\/ptn.primetime.ge\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptn.primetime.ge\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage","inLanguage":"en-US","url":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg","contentUrl":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg","width":654,"height":523},{"@type":"WebPage","@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage","url":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/","name":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1 - PTN.GE","isPartOf":{"@id":"https:\/\/ptn.primetime.ge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage"},"datePublished":"2020-11-25T09:23:37+00:00","dateModified":"2020-11-25T11:21:50+00:00","description":"\u201e\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8\u10e1 \u10e4\u10d4\u10d3\u10d4\u10e0\u10d0\u10ea\u10d8\u10d0\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8\u10e1 \u10e0\u10d4\u10d2\u10d8\u10dd\u10dc\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0 \u10ec\u10d0\u10e0\u10db\u10dd\u10d0\u10d3\u10d2\u10d4\u10dc\u10e1","breadcrumb":{"@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptn.primetime.ge\/"},{"@type":"ListItem","position":2,"name":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1"}]},{"@type":"Article","@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#article","isPartOf":{"@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage"},"author":{"@id":"https:\/\/ptn.primetime.ge\/#\/schema\/person\/f43bc888f884ee76c0ce504279c2c399"},"headline":"\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e3\u10ec\u10e7\u10d4\u10d1\u10d0 \u10d2\u10db\u10dd\u10d1\u10e1, \u10e0\u10e3\u10e1\u10d4\u10d7\u10e1\u10d0 \u10d3\u10d0 \u10dd\u10d9\u10e3\u10de\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10e1 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d8 \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0 \u10d4\u10d9\u10dd\u10dc\u10dd\u10db\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e1\u10d8\u10d5\u10e0\u10ea\u10d8\u10e1 \u10e4\u10dd\u10e0\u10db\u10d8\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d8\u10e1 \u10d3\u10d0\u10db\u10e2\u10d9\u10d8\u10ea\u10d4\u10d1\u10d0\u10e1","datePublished":"2020-11-25T09:23:37+00:00","dateModified":"2020-11-25T11:21:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#webpage"},"wordCount":3,"commentCount":0,"publisher":{"@id":"https:\/\/ptn.primetime.ge\/#organization"},"image":{"@id":"https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#primaryimage"},"thumbnailUrl":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/11\/cms-image-000015516.jpg","keywords":["\u10d3\u10d4 \u10e4\u10d0\u10e5\u10e2\u10dd \u10d0\u10e4\u10ee\u10d0\u10d6\u10d4\u10d7\u10d8","\u10dd\u10d9\u10e3\u10de\u10d0\u10ea\u10d8\u10d0","\u10e0\u10e3\u10e1\u10d4\u10d7\u10d8","\u10e1\u10d0\u10d2\u10d0\u10e0\u10d4\u10dd \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd"],"articleSection":["\u10de\u10dd\u10da\u10d8\u10e2\u10d8\u10d9\u10d0"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ptn.primetime.ge\/en\/sagareo-utsqheba-gmobs-rusethsa-da-okupirebul-aphkhazeths-shoris-erthiani-sotsialuri-da-ekonomikuri-sivrtsis-phormirebis-shesakheb-programis-damtkitsebas\/#respond"]}]},{"@type":"Person","@id":"https:\/\/ptn.primetime.ge\/#\/schema\/person\/f43bc888f884ee76c0ce504279c2c399","name":"salome","image":{"@type":"ImageObject","@id":"https:\/\/ptn.primetime.ge\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/ce7c36b03612e72bdefcb1a00658c5b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce7c36b03612e72bdefcb1a00658c5b0?s=96&d=mm&r=g","caption":"salome"},"url":"https:\/\/ptn.primetime.ge\/en\/author\/salome\/"}]}},"_links":{"self":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/posts\/60164"}],"collection":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/comments?post=60164"}],"version-history":[{"count":2,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/posts\/60164\/revisions"}],"predecessor-version":[{"id":60185,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/posts\/60164\/revisions\/60185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/media\/60167"}],"wp:attachment":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/media?parent=60164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/categories?post=60164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/tags?post=60164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}