{"id":702,"count":11,"description":"","link":"https:\/\/ptn.primetime.ge\/en\/tag\/ekaterine-dgebuadze\/","name":"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4","slug":"ekaterine-dgebuadze","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4 Archives - PTN.GE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptn.primetime.ge\/en\/tag\/ekaterine-dgebuadze\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4 Archives - PTN.GE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptn.primetime.ge\/en\/tag\/ekaterine-dgebuadze\/\" \/>\n<meta property=\"og:site_name\" content=\"PTN.GE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/ptn.primetime.ge\/#organization\",\"name\":\"PTN.GE\",\"url\":\"https:\/\/ptn.primetime.ge\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ptn.primetime.ge\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png\",\"contentUrl\":\"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png\",\"width\":250,\"height\":250,\"caption\":\"PTN.GE\"},\"image\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ptn.primetime.ge\/#website\",\"url\":\"https:\/\/ptn.primetime.ge\/\",\"name\":\"PTN.GE\",\"description\":\"\\u10e1\\u10d0\\u10d8\\u10dc\\u10e4\\u10dd\\u10e0\\u10db\\u10d0\\u10ea\\u10d8\\u10dd \\u10de\\u10dd\\u10e0\\u10e2\\u10d0\\u10da\\u10d8\",\"publisher\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ptn.primetime.ge\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#webpage\",\"url\":\"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/\",\"name\":\"\\u10d4\\u10d9\\u10d0\\u10e2\\u10d4\\u10e0\\u10d8\\u10dc\\u10d4 \\u10d3\\u10d2\\u10d4\\u10d1\\u10e3\\u10d0\\u10eb\\u10d4 Archives - PTN.GE\",\"isPartOf\":{\"@id\":\"https:\/\/ptn.primetime.ge\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ptn.primetime.ge\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u10d4\\u10d9\\u10d0\\u10e2\\u10d4\\u10e0\\u10d8\\u10dc\\u10d4 \\u10d3\\u10d2\\u10d4\\u10d1\\u10e3\\u10d0\\u10eb\\u10d4\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4 Archives - PTN.GE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptn.primetime.ge\/en\/tag\/ekaterine-dgebuadze\/","og_locale":"en_US","og_type":"article","og_title":"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4 Archives - PTN.GE","og_url":"https:\/\/ptn.primetime.ge\/en\/tag\/ekaterine-dgebuadze\/","og_site_name":"PTN.GE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/ptn.primetime.ge\/#organization","name":"PTN.GE","url":"https:\/\/ptn.primetime.ge\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/ptn.primetime.ge\/#logo","inLanguage":"en-US","url":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png","contentUrl":"https:\/\/ptn.primetime.ge\/wp-content\/uploads\/2020\/09\/Untitled-2.png","width":250,"height":250,"caption":"PTN.GE"},"image":{"@id":"https:\/\/ptn.primetime.ge\/#logo"}},{"@type":"WebSite","@id":"https:\/\/ptn.primetime.ge\/#website","url":"https:\/\/ptn.primetime.ge\/","name":"PTN.GE","description":"\u10e1\u10d0\u10d8\u10dc\u10e4\u10dd\u10e0\u10db\u10d0\u10ea\u10d8\u10dd \u10de\u10dd\u10e0\u10e2\u10d0\u10da\u10d8","publisher":{"@id":"https:\/\/ptn.primetime.ge\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptn.primetime.ge\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#webpage","url":"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/","name":"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4 Archives - PTN.GE","isPartOf":{"@id":"https:\/\/ptn.primetime.ge\/#website"},"breadcrumb":{"@id":"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ptn.primetime.ge\/tag\/ekaterine-dgebuadze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptn.primetime.ge\/"},{"@type":"ListItem","position":2,"name":"\u10d4\u10d9\u10d0\u10e2\u10d4\u10e0\u10d8\u10dc\u10d4 \u10d3\u10d2\u10d4\u10d1\u10e3\u10d0\u10eb\u10d4"}]}]}},"_links":{"self":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/tags\/702"}],"collection":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptn.primetime.ge\/en\/wp-json\/wp\/v2\/posts?tags=702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}